{"id":95733,"date":"2019-09-12T11:25:48","date_gmt":"2019-09-12T15:25:48","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=95733"},"modified":"2019-09-12T11:25:48","modified_gmt":"2019-09-12T15:25:48","slug":"la-caasd-informa-registro-leve-mejoria-en-la-produccion-de-agua-potable","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/09\/12\/la-caasd-informa-registro-leve-mejoria-en-la-produccion-de-agua-potable\/","title":{"rendered":"La CAASD informa registr\u00f3 leve mejor\u00eda en la producci\u00f3n de agua potable"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-95734 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/09\/caa.jpg\" alt=\"\" width=\"494\" height=\"332\" \/>SANTO DOMINGO.- La Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD) inform\u00f3 este mi\u00e9rcoles de una ligera mejor\u00eda en los niveles de agua embalsada, aunque sigue siendo necesario que llueva para paliar la actual situaci\u00f3n de crisis h\u00eddrica.<\/p>\n<p>En un comunicado, la entidad indic\u00f3 que la presa de Valdesia aument\u00f3 un cent\u00edmetro en sus niveles de almacenamiento de agua, mientras que la presa de Jig\u00fcey increment\u00f3 53 cent\u00edmetros sus reservas, producto de algunas lluvias originadas en la vertiente sur de la Cordillera Central.<\/p>\n<p>De igual manera, en la cuenca alta del r\u00edo Haina se produjeron algunas precipitaciones que aumentaron los caudales de este afluente y del r\u00edo Duey.<\/p>\n<p>\u201cEsto nos ha ayudado a que ayer y hoy el d\u00e9ficit en la producci\u00f3n de agua potable haya disminuido en unos ocho millones de galones al d\u00eda, es decir, que hoy estamos produciendo 348 millones de galones\u201d, precis\u00f3 el director general de la CAASD, Alejandro Mont\u00e1s.<\/p>\n<p>\u201cAunque hemos tenido esa mejor\u00eda, es necesario seguir observando el comportamiento de las lluvias y, debido a que tenemos una sequ\u00eda tan prolongada, el nivel de filtraci\u00f3n que se registra en los suelos es bien alto\u201d, aclar\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- La Corporaci\u00f3n del Acueducto y Alcantarillado de Santo Domingo (CAASD) inform\u00f3 este mi\u00e9rcoles de una ligera mejor\u00eda en los niveles de agua embalsada, aunque sigue siendo necesario que llueva para paliar la actual situaci\u00f3n de crisis h\u00eddrica. En un comunicado, la entidad indic\u00f3 que la presa de Valdesia aument\u00f3 un cent\u00edmetro en sus niveles de almacenamiento de agua, mientras que la presa de Jig\u00fcey increment\u00f3 53 cent\u00edmetros sus reservas, producto de algunas lluvias originadas en la vertiente sur de la Cordillera Central. De igual manera, en la cuenca alta del r\u00edo Haina se produjeron algunas precipitaciones que aumentaron los caudales de este afluente y del r\u00edo Duey. \u201cEsto nos ha ayudado a que ayer y hoy el d\u00e9ficit en la producci\u00f3n de agua potable haya disminuido en unos ocho millones de galones al d\u00eda, es decir, que hoy estamos produciendo 348 millones de galones\u201d, precis\u00f3 el director general de la CAASD, Alejandro Mont\u00e1s. \u201cAunque hemos tenido esa mejor\u00eda, es necesario seguir observando el comportamiento de las lluvias y, debido a que tenemos una sequ\u00eda tan prolongada, el nivel de filtraci\u00f3n que se registra en los suelos es bien alto\u201d, aclar\u00f3.<\/p>\n","protected":false},"author":8,"featured_media":95734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-95733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=95733"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95733\/revisions"}],"predecessor-version":[{"id":95735,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/95733\/revisions\/95735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/95734"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=95733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=95733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=95733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}