{"id":97501,"date":"2019-10-31T18:57:20","date_gmt":"2019-10-31T22:57:20","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=97501"},"modified":"2019-10-31T18:57:20","modified_gmt":"2019-10-31T22:57:20","slug":"dominicano-luis-mejia-oviedo-fue-elegido-como-presidente-de-la-odecabe","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/10\/31\/dominicano-luis-mejia-oviedo-fue-elegido-como-presidente-de-la-odecabe\/","title":{"rendered":"Dominicano Luis Mej\u00eda Oviedo fue elegido como presidente de la Odecabe"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-97502 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/10\/IMG-20191031-WA0143-1024x550-800x430.jpg\" alt=\"\" width=\"497\" height=\"267\" \/>SANTO DOMINGO.-El dominicano Luis Mej\u00eda Oviedo fue escogido como presidente de la Organizaci\u00f3n Deportiva Centroamericana y del Caribe (Odecabe), en la Asamblea General Eleccionaria de la instituci\u00f3n este jueves en Panam\u00e1.<\/p>\n<p>Mej\u00eda Oviedo, presidente del Comit\u00e9 Ol\u00edmpico Dominicano (COD) es ahora el segundo dominicano que alcanza en la posici\u00f3n. Se recuerda que el doctor Jos\u00e9 Joaqu\u00edn Puello presidi\u00f3 ese organismo por varios per\u00edodos.<\/p>\n<p>La asamblea se desarroll\u00f3 entre mi\u00e9rcoles y jueves en el hotel Wyndham Albroock de ciudad Panam\u00e1 hasta el jueves.<\/p>\n<p>La nueva direcci\u00f3n ejecutiva de la Odecabe tendr\u00e1 un periodo de 2019-2023.<\/p>\n<p>La primera vice presidencia ser\u00e1 Jimena Saldana, de M\u00e9xico; 2da vicepresidenta, Ciro Solano, de Colombia; tercera vicepresidenta, Sara Rosario, de Puerto Rico; tesorero, Camilo Amado de Panm\u00e1; adem\u00e1s de los vocales Judy Simmons, de Bermudas; Ruperto Herrera, Cuba; Cristopher Samuda, Jamaica.<\/p>\n<p>Mej\u00eda Oviedo es miembro del Comit\u00e9 Ol\u00edmpico\u00a0Internacional y es uno de los dirigentes m\u00e1s activo en la regi\u00f3n. Est\u00e1 acompa\u00f1ado por Gilberto Garc\u00eda, quien estuvo a la asamblea en su condici\u00f3n de Secretario General del COD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-El dominicano Luis Mej\u00eda Oviedo fue escogido como presidente de la Organizaci\u00f3n Deportiva Centroamericana y del Caribe (Odecabe), en la Asamblea General Eleccionaria de la instituci\u00f3n este jueves en Panam\u00e1. Mej\u00eda Oviedo, presidente del Comit\u00e9 Ol\u00edmpico Dominicano (COD) es ahora el segundo dominicano que alcanza en la posici\u00f3n. Se recuerda que el doctor Jos\u00e9 Joaqu\u00edn Puello presidi\u00f3 ese organismo por varios per\u00edodos. La asamblea se desarroll\u00f3 entre mi\u00e9rcoles y jueves en el hotel Wyndham Albroock de ciudad Panam\u00e1 hasta el jueves. La nueva direcci\u00f3n ejecutiva de la Odecabe tendr\u00e1 un periodo de 2019-2023. La primera vice presidencia ser\u00e1 Jimena Saldana, de M\u00e9xico; 2da vicepresidenta, Ciro Solano, de Colombia; tercera vicepresidenta, Sara Rosario, de Puerto Rico; tesorero, Camilo Amado de Panm\u00e1; adem\u00e1s de los vocales Judy Simmons, de Bermudas; Ruperto Herrera, Cuba; Cristopher Samuda, Jamaica. Mej\u00eda Oviedo es miembro del Comit\u00e9 Ol\u00edmpico\u00a0Internacional y es uno de los dirigentes m\u00e1s activo en la regi\u00f3n. Est\u00e1 acompa\u00f1ado por Gilberto Garc\u00eda, quien estuvo a la asamblea en su condici\u00f3n de Secretario General del COD.<\/p>\n","protected":false},"author":6,"featured_media":97502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-97501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=97501"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97501\/revisions"}],"predecessor-version":[{"id":97503,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97501\/revisions\/97503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/97502"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=97501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=97501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=97501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}