{"id":97714,"date":"2019-11-07T09:34:12","date_gmt":"2019-11-07T13:34:12","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=97714"},"modified":"2019-11-07T09:34:12","modified_gmt":"2019-11-07T13:34:12","slug":"pgr-y-ministerio-de-la-juventud-impulsaran-educacion-jovenes-sobrevivientes-de-violencia","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/11\/07\/pgr-y-ministerio-de-la-juventud-impulsaran-educacion-jovenes-sobrevivientes-de-violencia\/","title":{"rendered":"PGR y Ministerio de la Juventud impulsar\u00e1n educaci\u00f3n j\u00f3venes sobrevivientes de violencia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-97715 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/11\/UN-ACUERDO-1024x550-800x430.jpg\" alt=\"\" width=\"499\" height=\"268\" \/>SANTO DOMINGO.-La Procuradur\u00eda General de la Rep\u00fablica (PGR) y el Ministerio de la Juventud (MJ) realizan las coordinaciones de lugar para impulsar acciones conjuntas que incentiven el desarrollo integral de las j\u00f3venes en situaciones de vulnerabilidad, sobrevivientes de violencia de g\u00e9nero, as\u00ed como de sus hijos o hijas, proporcion\u00e1ndoles acceso a la educaci\u00f3n t\u00e9cnica y profesional.<\/p>\n<p>Mediante un acuerdo de cooperaci\u00f3n interinstitucional firmado por el procurador general de la Rep\u00fablica, Jean Rodr\u00edguez, y la ministra de la Juventud Robiamny Balc\u00e1cer, ambas instituciones se comprometieron a promover, incentivar e impulsar a las sobrevivientes de violencia a que se integren al sistema educativo superior y t\u00e9cnico, con la finalidad de que en un futuro puedan insertarse con \u00e9xito en el sistema socioecon\u00f3mico nacional.<\/p>\n<p>El procurador Jean Rodr\u00edguez expres\u00f3 que esta es la primera vez que se realiza un acuerdo de esta naturaleza, el cual dijo que va a impactar positivamente a las sobrevivientes de violencia.<\/p>\n<p>\u201cEl hecho de que las sobrevivientes de violencia y sus familiares puedan recibir becas canalizadas por el Ministerio de la Juventud, as\u00ed como tambi\u00e9n los cursos de capacitaci\u00f3n que vamos a trabajar de manera conjunta, eso va a tener un impacto \u00fanico y especial en el desarrollo de nuestra juventud y de nuestra ciudadan\u00eda\u201d, manifest\u00f3 tras agradecer a la ministra de la juventud y a su equipo de trabajo por sumarse a la iniciativa.<\/p>\n<p>De su lado, la ministra Robiamny Balc\u00e1cer dijo que se trata de un acuerdo que va a beneficiar a mujeres valientes y a sus hijos. \u201cA m\u00ed, de manera muy especial, me llena de gran satisfacci\u00f3n poder ser parte de esta iniciativa, porque desde mis inicios en la labor comunitaria hemos apoyado el combate de la violencia de g\u00e9nero e intrafamiliar\u201d, expres\u00f3.<\/p>\n<p>Agreg\u00f3: \u201cpoder aportar desde el Ministerio de la Juventud a que tengan una segunda oportunidad, tanto ellas como sus hijos, a nosotros nos complace y sentimos que una vez m\u00e1s pues dejamos las palabras a un lado, para entonces sostenernos en los hechos\u201d.<\/p>\n<p>El acuerdo interinstitucional establece que la PGR facilitar\u00e1 las aulas de la Escuela Nacional del Ministerio P\u00fablico (ENMP) para el desarrollo de las actividades de capacitaci\u00f3n, seg\u00fan disponibilidad, adem\u00e1s de que dar\u00e1 asistencia a los beneficiarios, ofert\u00e1ndoles espacios de interacci\u00f3n digital para que puedan culminar el proceso formativo. Tambi\u00e9n, acompa\u00f1ar\u00e1 en el proceso de inscripci\u00f3n y seguimiento a los y las becadas por el MJ.<\/p>\n<p>En tanto que el MJ otorgar\u00e1 becas a nivel de grado, postgrado, del idioma ingl\u00e9s, cursos t\u00e9cnicos y de competencias digitales a trav\u00e9s del programa de becas Agentes del Cambio, Act\u00edvate con Rep\u00fablica Digital y Jornadas Juventud + Digital, seg\u00fan disponibilidad y ofrecer\u00e1 un trato preferencial a las sobrevivientes de violencia de g\u00e9nero y a uno de sus hijos o hijas en las convocatorias ordinarias de becas que realiza el Ministerio, en el caso que aplique.<\/p>\n<p>El convenio tendr\u00e1 dos a\u00f1os de duraci\u00f3n y fue firmado en la sede de la Procuradur\u00eda General de la Rep\u00fablica con la participaci\u00f3n de otros funcionarios de estas instituciones, entre ellos, de la rectora de la Escuela Nacional del Ministerio P\u00fablico, Gladys S\u00e1nchez, y la titular de la Direcci\u00f3n Contra la Violencia de G\u00e9nero del Ministerio P\u00fablico, Ana Andrea Villa Camacho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-La Procuradur\u00eda General de la Rep\u00fablica (PGR) y el Ministerio de la Juventud (MJ) realizan las coordinaciones de lugar para impulsar acciones conjuntas que incentiven el desarrollo integral de las j\u00f3venes en situaciones de vulnerabilidad, sobrevivientes de violencia de g\u00e9nero, as\u00ed como de sus hijos o hijas, proporcion\u00e1ndoles acceso a la educaci\u00f3n t\u00e9cnica y profesional. Mediante un acuerdo de cooperaci\u00f3n interinstitucional firmado por el procurador general de la Rep\u00fablica, Jean Rodr\u00edguez, y la ministra de la Juventud Robiamny Balc\u00e1cer, ambas instituciones se comprometieron a promover, incentivar e impulsar a las sobrevivientes de violencia a que se integren al sistema educativo superior y t\u00e9cnico, con la finalidad de que en un futuro puedan insertarse con \u00e9xito en el sistema socioecon\u00f3mico nacional. El procurador Jean Rodr\u00edguez expres\u00f3 que esta es la primera vez que se realiza un acuerdo de esta naturaleza, el cual dijo que va a impactar positivamente a las sobrevivientes de violencia. \u201cEl hecho de que las sobrevivientes de violencia y sus familiares puedan recibir becas canalizadas por el Ministerio de la Juventud, as\u00ed como tambi\u00e9n los cursos de capacitaci\u00f3n que vamos a trabajar de manera conjunta, eso va a tener un impacto \u00fanico y especial en el desarrollo de nuestra juventud y de nuestra ciudadan\u00eda\u201d, manifest\u00f3 tras agradecer a la ministra de la juventud y a su equipo de trabajo por sumarse a la iniciativa. De su lado, la ministra Robiamny Balc\u00e1cer dijo que se trata de un acuerdo que va a beneficiar a mujeres valientes y a sus hijos. \u201cA m\u00ed, de manera muy especial, me llena de gran satisfacci\u00f3n poder ser parte de esta iniciativa, porque desde mis inicios en la labor comunitaria hemos apoyado el combate de la violencia de g\u00e9nero e intrafamiliar\u201d, expres\u00f3. Agreg\u00f3: \u201cpoder aportar desde el Ministerio de la Juventud a que tengan una segunda oportunidad, tanto ellas como sus hijos, a nosotros nos complace y sentimos que una vez m\u00e1s pues dejamos las palabras a un lado, para entonces sostenernos en los hechos\u201d. El acuerdo interinstitucional establece que la PGR facilitar\u00e1 las aulas de la Escuela Nacional del Ministerio P\u00fablico (ENMP) para el desarrollo de las actividades de capacitaci\u00f3n, seg\u00fan disponibilidad, adem\u00e1s de que dar\u00e1 asistencia a los beneficiarios, ofert\u00e1ndoles espacios de interacci\u00f3n digital para que puedan culminar el proceso formativo. Tambi\u00e9n, acompa\u00f1ar\u00e1 en el proceso de inscripci\u00f3n y seguimiento a los y las becadas por el MJ. En tanto que el MJ otorgar\u00e1 becas a nivel de grado, postgrado, del idioma ingl\u00e9s, cursos t\u00e9cnicos y de competencias digitales a trav\u00e9s del programa de becas Agentes del Cambio, Act\u00edvate con Rep\u00fablica Digital y Jornadas Juventud + Digital, seg\u00fan disponibilidad y ofrecer\u00e1 un trato preferencial a las sobrevivientes de violencia de g\u00e9nero y a uno de sus hijos o hijas en las convocatorias ordinarias de becas que realiza el Ministerio, en el caso que aplique. El convenio tendr\u00e1 dos a\u00f1os de duraci\u00f3n y fue firmado en la sede de la Procuradur\u00eda General de la Rep\u00fablica con la participaci\u00f3n de otros funcionarios de estas instituciones, entre ellos, de la rectora de la Escuela Nacional del Ministerio P\u00fablico, Gladys S\u00e1nchez, y la titular de la Direcci\u00f3n Contra la Violencia de G\u00e9nero del Ministerio P\u00fablico, Ana Andrea Villa Camacho.<\/p>\n","protected":false},"author":6,"featured_media":97715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-97714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=97714"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97714\/revisions"}],"predecessor-version":[{"id":97716,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97714\/revisions\/97716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/97715"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=97714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=97714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=97714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}