{"id":97839,"date":"2019-11-12T12:35:00","date_gmt":"2019-11-12T16:35:00","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=97839"},"modified":"2019-11-12T12:35:00","modified_gmt":"2019-11-12T16:35:00","slug":"capacitaran-26271-hogares-en-proteccion-social-frente-a-choques-climaticos","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2019\/11\/12\/capacitaran-26271-hogares-en-proteccion-social-frente-a-choques-climaticos\/","title":{"rendered":"Capacitar\u00e1n 26,271 hogares en protecci\u00f3n social frente a choques clim\u00e1ticos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-97841 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2019\/11\/Foto-principal-1024x550-1-800x430.jpeg\" alt=\"\" width=\"495\" height=\"266\" \/>SANTO DOMINGO. \u2013\u00a0La\u00a0Vicepresidencia\u00a0de la Rep\u00fablica, el Programa de las Naciones Unidas para el Desarrollo (PNUD) y el Fondo de las Naciones Unidas para la Infancia (Unicef) informaron mediante un comunicado que \u00a0desarrollaron un programa de entrenamiento piloto del Protocolo Nacional de actuaci\u00f3n para la protecci\u00f3n social frente a choques clim\u00e1ticos.<\/p>\n<p>El programa, perteneciente al Gabinete de Coordinaci\u00f3n de Pol\u00edticas Sociales (GCPS), est\u00e1 dirigido a capacitar inicialmente a 26 mil 271 hogares de las Provincias El Seibo y Montecristi en situaci\u00f3n de pobreza, que se encuentran en condiciones de vulnerabilidad y expuestos a diferentes eventos y desastres naturales.<\/p>\n<p>Explicaron que para lograr la meta, la instituci\u00f3n y los organismos internacionales entrenaron durante cuatro d\u00edas a 23 encargados de los departamentos de Operaciones del programa Progresando con Solidaridad (Prosoli) , y de la Escuela Nacional de Gesti\u00f3n de Riesgo de la Comisi\u00f3n Nacional de Emergencia y Defensa Civil, quienes tendr\u00e1n la responsabilidad de replicar los conocimientos entre el grupo de familias.<\/p>\n<p>La iniciativa liderada por el GCPS, que coordina la vicepresidenta de la Rep\u00fablica, doctora Margarita Cede\u00f1o, busca ofrecer experiencias novedosas y pertinentes para proteger en forma integral a los hogares dominicanos que est\u00e9n ubicados en zonas de alto riesgo ante choques clim\u00e1ticos y contribuye con los Objetivos de Desarrollo Sostenible (ODS) de la Agenda 2030\u00a0 directamente: ODS 1 Fin de la pobreza, ODS 11 Ciudades y comunidades resilientes y\u00a0 ODS 14 Acci\u00f3n por el clima.<\/p>\n<p>Agrega que la misma busca desarrollar un enfoque de protecci\u00f3n social que llegue a los hogares que m\u00e1s fragilidad tienen y ofrecerles acompa\u00f1amiento social, orientaci\u00f3n y acceso a informaci\u00f3n relevante sobre las medidas y mecanismos de protecci\u00f3n, adem\u00e1s de fortalecer sus redes de apoyo sociales y de relacionamiento con el Estado dominicano, para ser mucho m\u00e1s resilientes ante los eventos que los puedan afectar, como las inundaciones, huracanes y tormentas tropicales.<\/p>\n<p>Cede\u00f1o de Fern\u00e1ndez, \u00a0manifest\u00f3 que est\u00e1 preocupada por los efectos negativos que provocan los desastres naturales a las personas vulnerables; en ese sentido se cre\u00f3 el \u00cdndice de Vulnerabilidad ante Choques Clim\u00e1ticos (IVACC) realizado por el Siuben, para desarrollar acciones que permitan menguar los efectos de dichos fen\u00f3menos.<\/p>\n<p>\u201cCon esta propuesta buscamos fortalecer los procesos preventivos y evitar que las familias vulnerables con las que hemos logrado avances significativos se vean afectadas por los choques clim\u00e1ticos, tema que para nuestro Gobierno es de vital importancia, ya que permitir\u00e1 garantizar el bienestar de la poblaci\u00f3n y cumplir con nuestro compromiso de reducir la pobreza a su m\u00ednima expresi\u00f3n\u201d, expres\u00f3.<\/p>\n<p>Durante la actividad particip\u00f3 el director interinstitucional de Planificaci\u00f3n de la\u00a0Vicepresidencia, Ezequiel V\u00f3lquez; y de Operaciones, Delvin Quezada, con el apoyo de la asesora de Gesti\u00f3n de Riesgos de Programa de las Naciones Unidas (PNUD), Ana Mar\u00eda P\u00e9rez Casta\u00f1o, y el oficial de Pol\u00edticas Sociales de Unicef, Gavino Severino.<\/p>\n<p>El taller fue impartido por los consultores internacionales del PNUD y Unicef, Juan Carlos Orrego y Magdalena Mart\u00ednez respectivamente, en unos de los salones de reuniones del Siuben, donde los representantes de los Departamentos de Operaciones de Prosoli participantes recibieron los certificados por haber cumplido con la asistencia establecida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. \u2013\u00a0La\u00a0Vicepresidencia\u00a0de la Rep\u00fablica, el Programa de las Naciones Unidas para el Desarrollo (PNUD) y el Fondo de las Naciones Unidas para la Infancia (Unicef) informaron mediante un comunicado que \u00a0desarrollaron un programa de entrenamiento piloto del Protocolo Nacional de actuaci\u00f3n para la protecci\u00f3n social frente a choques clim\u00e1ticos. El programa, perteneciente al Gabinete de Coordinaci\u00f3n de Pol\u00edticas Sociales (GCPS), est\u00e1 dirigido a capacitar inicialmente a 26 mil 271 hogares de las Provincias El Seibo y Montecristi en situaci\u00f3n de pobreza, que se encuentran en condiciones de vulnerabilidad y expuestos a diferentes eventos y desastres naturales. Explicaron que para lograr la meta, la instituci\u00f3n y los organismos internacionales entrenaron durante cuatro d\u00edas a 23 encargados de los departamentos de Operaciones del programa Progresando con Solidaridad (Prosoli) , y de la Escuela Nacional de Gesti\u00f3n de Riesgo de la Comisi\u00f3n Nacional de Emergencia y Defensa Civil, quienes tendr\u00e1n la responsabilidad de replicar los conocimientos entre el grupo de familias. La iniciativa liderada por el GCPS, que coordina la vicepresidenta de la Rep\u00fablica, doctora Margarita Cede\u00f1o, busca ofrecer experiencias novedosas y pertinentes para proteger en forma integral a los hogares dominicanos que est\u00e9n ubicados en zonas de alto riesgo ante choques clim\u00e1ticos y contribuye con los Objetivos de Desarrollo Sostenible (ODS) de la Agenda 2030\u00a0 directamente: ODS 1 Fin de la pobreza, ODS 11 Ciudades y comunidades resilientes y\u00a0 ODS 14 Acci\u00f3n por el clima. Agrega que la misma busca desarrollar un enfoque de protecci\u00f3n social que llegue a los hogares que m\u00e1s fragilidad tienen y ofrecerles acompa\u00f1amiento social, orientaci\u00f3n y acceso a informaci\u00f3n relevante sobre las medidas y mecanismos de protecci\u00f3n, adem\u00e1s de fortalecer sus redes de apoyo sociales y de relacionamiento con el Estado dominicano, para ser mucho m\u00e1s resilientes ante los eventos que los puedan afectar, como las inundaciones, huracanes y tormentas tropicales. Cede\u00f1o de Fern\u00e1ndez, \u00a0manifest\u00f3 que est\u00e1 preocupada por los efectos negativos que provocan los desastres naturales a las personas vulnerables; en ese sentido se cre\u00f3 el \u00cdndice de Vulnerabilidad ante Choques Clim\u00e1ticos (IVACC) realizado por el Siuben, para desarrollar acciones que permitan menguar los efectos de dichos fen\u00f3menos. \u201cCon esta propuesta buscamos fortalecer los procesos preventivos y evitar que las familias vulnerables con las que hemos logrado avances significativos se vean afectadas por los choques clim\u00e1ticos, tema que para nuestro Gobierno es de vital importancia, ya que permitir\u00e1 garantizar el bienestar de la poblaci\u00f3n y cumplir con nuestro compromiso de reducir la pobreza a su m\u00ednima expresi\u00f3n\u201d, expres\u00f3. Durante la actividad particip\u00f3 el director interinstitucional de Planificaci\u00f3n de la\u00a0Vicepresidencia, Ezequiel V\u00f3lquez; y de Operaciones, Delvin Quezada, con el apoyo de la asesora de Gesti\u00f3n de Riesgos de Programa de las Naciones Unidas (PNUD), Ana Mar\u00eda P\u00e9rez Casta\u00f1o, y el oficial de Pol\u00edticas Sociales de Unicef, Gavino Severino. El taller fue impartido por los consultores internacionales del PNUD y Unicef, Juan Carlos Orrego y Magdalena Mart\u00ednez respectivamente, en unos de los salones de reuniones del Siuben, donde los representantes de los Departamentos de Operaciones de Prosoli participantes recibieron los certificados por haber cumplido con la asistencia establecida.<\/p>\n","protected":false},"author":6,"featured_media":97841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-97839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=97839"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97839\/revisions"}],"predecessor-version":[{"id":97842,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/97839\/revisions\/97842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/97841"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=97839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=97839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=97839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}