{"id":98689,"date":"2020-01-09T09:53:49","date_gmt":"2020-01-09T13:53:49","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=98689"},"modified":"2020-01-09T09:53:49","modified_gmt":"2020-01-09T13:53:49","slug":"beber-te-frecuentemente-secreto-para-una-vida-mas-longeva-y-saludable-segun-estudio","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/01\/09\/beber-te-frecuentemente-secreto-para-una-vida-mas-longeva-y-saludable-segun-estudio\/","title":{"rendered":"Beber t\u00e9 frecuentemente, secreto para una vida m\u00e1s longeva y saludable, seg\u00fan estudio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-98690 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/01\/te2-1024x550-800x430.jpg\" alt=\"\" width=\"495\" height=\"266\" \/>LONDRES.- Beber t\u00e9 al menos tres veces por semana ha sido asociado con una vida m\u00e1s longeva y saludable, seg\u00fan un estudio publicado este jueves por la Sociedad Europea de Cardiolog\u00eda.<\/p>\n<p>\u201cEl consumo habitual de t\u00e9 est\u00e1 asociado con menores riesgos de (padecer) enfermedades cardiovasculares y muertes por todo tipo de causas\u201d, indic\u00f3 el principal autor de la investigaci\u00f3n, Xinyan Wang, de la Academia China de Ciencias M\u00e9dicas de Pek\u00edn.<\/p>\n<p>Ese experto remarc\u00f3 que \u201clos efectos favorables en la salud son m\u00e1s robustos en el caso del t\u00e9 verde y, en el largo plazo, para los bebedores habituales de t\u00e9\u201d en general.<\/p>\n<p>Para llegar a esos hallazgos, el equipo investigador realiz\u00f3 un an\u00e1lisis entre 100.902 participantes con un historial m\u00e9dico en el que no hab\u00edan sufrido ning\u00fan ataque al coraz\u00f3n, apoplej\u00eda o c\u00e1ncer.<\/p>\n<p>Se les clasific\u00f3 en dos grupos diferentes: los consumidores de t\u00e9 (que lo tomaban tres o m\u00e1s veces por semana) y aquellos que nunca lo probaban o no lo hac\u00edan habitualmente (personas que optaban por esa infusi\u00f3n menos de tres veces por semana). A todos se les hizo un seguimiento durante una media de 7,3 a\u00f1os.<\/p>\n<p>Estos experimentos demostraron que hab\u00eda una asociaci\u00f3n entre el consumo habitual de t\u00e9 con m\u00e1s a\u00f1os saludables de existencia y una mayor esperanza de vida.<\/p>\n<p>Como ejemplo, observaron que una persona de 50 a\u00f1os consumidora habitual de t\u00e9 desarrollar\u00eda enfermedades coronarias y apoplej\u00edas 1,41 a\u00f1os m\u00e1s tarde y vivir\u00eda 1,26 a\u00f1os m\u00e1s que otra que nunca lo tomaba.<\/p>\n<p>Frente a los participantes que nunca inger\u00edan esa infusi\u00f3n, o que lo hac\u00edan en raras ocasiones, los cient\u00edficos detectaron que los bebedores habituales ten\u00edan un 20 % menos de riesgo de sufrir un episodio de enfermedad coronaria y apoplej\u00eda; un peligro menor en un 22 % de padecer dolencias del coraz\u00f3n y apoplej\u00edas mortales, y un 15 % menos en la amenaza de muerte por todo tipo de causas.<\/p>\n<p>Los investigadores llevaron a cabo un nuevo estudio sobre la influencia potencial en los cambios de comportamiento de los consumidores de t\u00e9, en el que participaron 14.081 personas, a quienes se evalu\u00f3 en dos momentos diferentes, dejando 8,2 a\u00f1os entre medias y con un seguimiento tras la segunda evaluaci\u00f3n de 5,3 a\u00f1os.<\/p>\n<p>Aqu\u00ed, seg\u00fan la publicaci\u00f3n, vieron que los consumidores habituales que mantuvieron su h\u00e1bito en ambos momentos ten\u00edan un 39 % menos de riesgo de desarrollar patolog\u00edas card\u00edacas y un peligro menor en un 56 % de sufrir un ataque al coraz\u00f3n o apoplej\u00eda mortal.<\/p>\n<p>Tambi\u00e9n identificaron que el riesgo de muerte por todo tipo de causas en esas personas era un 29 % menor frente a los participantes que nunca tomaban t\u00e9 o lo hac\u00edan raramente.<\/p>\n<p>\u201cLos efectos protectores del t\u00e9 fueron m\u00e1s pronunciados entre el grupo de bebedores habituales\u201d, destac\u00f3 Dongfeng Gu, otro de los autores de la investigaci\u00f3n.<\/p>\n<p>Ese experto agreg\u00f3 que \u201cel principal componente bioactivo del t\u00e9, llamado polyfenol, no se almacena en el cuerpo en el largo plazo\u201d, por lo que puede que sea necesario su \u201cconsumo frecuente\u201d durante un periodo m\u00e1s extendido\u201d para \u201cel efecto cardioprotector\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LONDRES.- Beber t\u00e9 al menos tres veces por semana ha sido asociado con una vida m\u00e1s longeva y saludable, seg\u00fan un estudio publicado este jueves por la Sociedad Europea de Cardiolog\u00eda. \u201cEl consumo habitual de t\u00e9 est\u00e1 asociado con menores riesgos de (padecer) enfermedades cardiovasculares y muertes por todo tipo de causas\u201d, indic\u00f3 el principal autor de la investigaci\u00f3n, Xinyan Wang, de la Academia China de Ciencias M\u00e9dicas de Pek\u00edn. Ese experto remarc\u00f3 que \u201clos efectos favorables en la salud son m\u00e1s robustos en el caso del t\u00e9 verde y, en el largo plazo, para los bebedores habituales de t\u00e9\u201d en general. Para llegar a esos hallazgos, el equipo investigador realiz\u00f3 un an\u00e1lisis entre 100.902 participantes con un historial m\u00e9dico en el que no hab\u00edan sufrido ning\u00fan ataque al coraz\u00f3n, apoplej\u00eda o c\u00e1ncer. Se les clasific\u00f3 en dos grupos diferentes: los consumidores de t\u00e9 (que lo tomaban tres o m\u00e1s veces por semana) y aquellos que nunca lo probaban o no lo hac\u00edan habitualmente (personas que optaban por esa infusi\u00f3n menos de tres veces por semana). A todos se les hizo un seguimiento durante una media de 7,3 a\u00f1os. Estos experimentos demostraron que hab\u00eda una asociaci\u00f3n entre el consumo habitual de t\u00e9 con m\u00e1s a\u00f1os saludables de existencia y una mayor esperanza de vida. Como ejemplo, observaron que una persona de 50 a\u00f1os consumidora habitual de t\u00e9 desarrollar\u00eda enfermedades coronarias y apoplej\u00edas 1,41 a\u00f1os m\u00e1s tarde y vivir\u00eda 1,26 a\u00f1os m\u00e1s que otra que nunca lo tomaba. Frente a los participantes que nunca inger\u00edan esa infusi\u00f3n, o que lo hac\u00edan en raras ocasiones, los cient\u00edficos detectaron que los bebedores habituales ten\u00edan un 20 % menos de riesgo de sufrir un episodio de enfermedad coronaria y apoplej\u00eda; un peligro menor en un 22 % de padecer dolencias del coraz\u00f3n y apoplej\u00edas mortales, y un 15 % menos en la amenaza de muerte por todo tipo de causas. Los investigadores llevaron a cabo un nuevo estudio sobre la influencia potencial en los cambios de comportamiento de los consumidores de t\u00e9, en el que participaron 14.081 personas, a quienes se evalu\u00f3 en dos momentos diferentes, dejando 8,2 a\u00f1os entre medias y con un seguimiento tras la segunda evaluaci\u00f3n de 5,3 a\u00f1os. Aqu\u00ed, seg\u00fan la publicaci\u00f3n, vieron que los consumidores habituales que mantuvieron su h\u00e1bito en ambos momentos ten\u00edan un 39 % menos de riesgo de desarrollar patolog\u00edas card\u00edacas y un peligro menor en un 56 % de sufrir un ataque al coraz\u00f3n o apoplej\u00eda mortal. Tambi\u00e9n identificaron que el riesgo de muerte por todo tipo de causas en esas personas era un 29 % menor frente a los participantes que nunca tomaban t\u00e9 o lo hac\u00edan raramente. \u201cLos efectos protectores del t\u00e9 fueron m\u00e1s pronunciados entre el grupo de bebedores habituales\u201d, destac\u00f3 Dongfeng Gu, otro de los autores de la investigaci\u00f3n. Ese experto agreg\u00f3 que \u201cel principal componente bioactivo del t\u00e9, llamado polyfenol, no se almacena en el cuerpo en el largo plazo\u201d, por lo que puede que sea necesario su \u201cconsumo frecuente\u201d durante un periodo m\u00e1s extendido\u201d para \u201cel efecto cardioprotector\u201d.<\/p>\n","protected":false},"author":6,"featured_media":98690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-98689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nature"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/98689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=98689"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/98689\/revisions"}],"predecessor-version":[{"id":98691,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/98689\/revisions\/98691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/98690"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=98689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=98689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=98689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}