{"id":99658,"date":"2020-02-21T10:16:54","date_gmt":"2020-02-21T14:16:54","guid":{"rendered":"http:\/\/conexiondigital.com.do\/?p=99658"},"modified":"2020-02-21T10:16:54","modified_gmt":"2020-02-21T14:16:54","slug":"primer-ministro-de-lesoto-evita-vista-sobre-acusacion-de-asesinar-a-su-esposa","status":"publish","type":"post","link":"https:\/\/conexiondigital.com.do\/index.php\/2020\/02\/21\/primer-ministro-de-lesoto-evita-vista-sobre-acusacion-de-asesinar-a-su-esposa\/","title":{"rendered":"Primer ministro de Lesoto evita vista sobre acusaci\u00f3n de asesinar a su esposa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-99659 alignleft\" src=\"https:\/\/images.conexiondigital.com.do\/wp-content\/uploads\/2020\/02\/lesoto-2-primer-ministro.jpg\" alt=\"\" width=\"495\" height=\"330\" \/>JOHANNESBURGO.- El primer ministro de Lesoto, Thomas Thabane, no compareci\u00f3 hoy ante un tribunal en el que se le iba a acusar por el asesinato de su anterior esposa, Lipolelo, en 2017, en medio de informaciones period\u00edsticas que apuntan a que ha viajado a la vecina Sud\u00e1frica para recibir atenci\u00f3n m\u00e9dica.<\/p>\n<p>\u201cVamos a determinar d\u00f3nde est\u00e1 y los motivos por los que no se ha presentado\u201d en un tribunal de la capital del pa\u00eds, Maseru, declar\u00f3 a los periodistas el subcomisario de la Polic\u00eda, Paseka Mokete.<\/p>\n<p>\u201cA\u00fan tengo que reunirme con su abogado. Despu\u00e9s de hablar con su abogado estar\u00e9 en condiciones de decir si procedemos o no\u201d con la vista, se\u00f1al\u00f3 Mokete en declaraciones divulgadas por los medios locales.<\/p>\n<p>Preguntado si el primer ministro est\u00e1 en Lesoto o ha viajado a Sud\u00e1frica, como aseguraron algunos medios, el subcomisario respondi\u00f3: \u201cno estamos en condiciones de confirmar eso\u201d.<\/p>\n<p>Thabane, de 80 a\u00f1os, anunci\u00f3 este jueves que dimitir\u00e1 de su cargo\u00a0 a finales de julio a m\u00e1s tardar, despu\u00e9s de que la Polic\u00eda confirmara que era inminente una acusaci\u00f3n oficial contra \u00e9l por el asesinato de su anterior esposa, Lipolelo.<\/p>\n<p>El mandatario hab\u00eda anticipado ya su salida del cargo hace un mes aludiendo a su avanzada edad, si bien entonces no fij\u00f3 fecha.<\/p>\n<p>El gobernante se vio forzado a dar ese paso por la presi\u00f3n de su partido y en medio de un creciente esc\u00e1ndalo por la presunta implicaci\u00f3n de su actual esposa, Maesaiah Thabane, en el crimen de su primera mujer.<\/p>\n<p>Maesaiah est\u00e1 acusada oficialmente de asesinato desde principios de este mes.<\/p>\n<p>Lipolelo Thabane fue tiroteada a las puertas de su casa dos d\u00edas antes de que Thomas Thabane tomase posesi\u00f3n como primer ministro.<\/p>\n<p>Thabane y Lipolelo hab\u00edan iniciado a\u00f1os antes los tr\u00e1mites de un complicado divorcio, pero el proceso no hab\u00eda concluido a\u00fan cuando el l\u00edder lesotense volvi\u00f3 a ser elegido \u2013 por segunda vez en su carrera \u2013 para ocupar el cargo de primer ministro.<\/p>\n<p>Un mes despu\u00e9s de la muerte, Thabane contrajo matrimonio con Maesaiah y \u00e9sta pas\u00f3 a ser oficialmente primera dama del pa\u00eds.<\/p>\n<p>Las especulaciones sobre la presunta implicaci\u00f3n de Maesaiah en el crimen no son nuevas, si bien la situaci\u00f3n de los Thabane se complic\u00f3 especialmente a partir de diciembre de 2019.<\/p>\n<p>En esas fechas sali\u00f3 a la luz de una carta del jefe de la Polic\u00eda del pa\u00eds, Holomo Molibeli, en la que afirmaba tener pruebas de que se hab\u00edan hecho llamadas al n\u00famero del primer ministro desde el lugar de la muerte de Lipo Lelo Thabane.<\/p>\n<p>Las acusaciones se conocieron, adem\u00e1s, tras meses de grave crisis interna en el seno del oficialista Congreso de Todos los Basoto (ABC, por sus siglas en ingl\u00e9s), con lo que los afines a Thabane y a su actual esposa relacionaron \u2013 y contin\u00faan relacionando \u2013 las acusaciones con las aspiraciones pol\u00edticas de las facciones rivales.<\/p>\n<p>La primera dama tuvo que comparecer el pasado martes en una vista judicial preliminar como acusada de asesinato y deber\u00e1 volver a hacerlo el pr\u00f3ximo 17 de marzo.<\/p>\n<p>Su situaci\u00f3n actual es de libertad bajo fianza, pese a que en enero la mujer huy\u00f3 brevemente a Sud\u00e1frica, ayudada por su portavoz, cuando la Polic\u00eda la cit\u00f3 a declarar (sin haber interpuesto a\u00fan cargos) y permaneci\u00f3 en paradero desconocido durante unos d\u00edas.<\/p>\n<p>El propio partido ABC tiene problemas para elegir al posible sucesor de Thabane y se debate entre varios aspirantes rivales.<\/p>\n<p>Esta situaci\u00f3n amenaza con desatar una nueva oleada de inestabilidad pol\u00edtica en este peque\u00f1o reino monta\u00f1oso enclavado geogr\u00e1ficamente en medio de Sud\u00e1frica.<\/p>\n<p>La monarqu\u00eda constitucional de Lesoto, encabezada actualmente por el rey Letsie III, quien no tiene poder ejecutivo, ha vivido numerosos golpes de Estado desde que el pa\u00eds se independiz\u00f3 del Reino Unido en 1966.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOHANNESBURGO.- El primer ministro de Lesoto, Thomas Thabane, no compareci\u00f3 hoy ante un tribunal en el que se le iba a acusar por el asesinato de su anterior esposa, Lipolelo, en 2017, en medio de informaciones period\u00edsticas que apuntan a que ha viajado a la vecina Sud\u00e1frica para recibir atenci\u00f3n m\u00e9dica. \u201cVamos a determinar d\u00f3nde est\u00e1 y los motivos por los que no se ha presentado\u201d en un tribunal de la capital del pa\u00eds, Maseru, declar\u00f3 a los periodistas el subcomisario de la Polic\u00eda, Paseka Mokete. \u201cA\u00fan tengo que reunirme con su abogado. Despu\u00e9s de hablar con su abogado estar\u00e9 en condiciones de decir si procedemos o no\u201d con la vista, se\u00f1al\u00f3 Mokete en declaraciones divulgadas por los medios locales. Preguntado si el primer ministro est\u00e1 en Lesoto o ha viajado a Sud\u00e1frica, como aseguraron algunos medios, el subcomisario respondi\u00f3: \u201cno estamos en condiciones de confirmar eso\u201d. Thabane, de 80 a\u00f1os, anunci\u00f3 este jueves que dimitir\u00e1 de su cargo\u00a0 a finales de julio a m\u00e1s tardar, despu\u00e9s de que la Polic\u00eda confirmara que era inminente una acusaci\u00f3n oficial contra \u00e9l por el asesinato de su anterior esposa, Lipolelo. El mandatario hab\u00eda anticipado ya su salida del cargo hace un mes aludiendo a su avanzada edad, si bien entonces no fij\u00f3 fecha. El gobernante se vio forzado a dar ese paso por la presi\u00f3n de su partido y en medio de un creciente esc\u00e1ndalo por la presunta implicaci\u00f3n de su actual esposa, Maesaiah Thabane, en el crimen de su primera mujer. Maesaiah est\u00e1 acusada oficialmente de asesinato desde principios de este mes. Lipolelo Thabane fue tiroteada a las puertas de su casa dos d\u00edas antes de que Thomas Thabane tomase posesi\u00f3n como primer ministro. Thabane y Lipolelo hab\u00edan iniciado a\u00f1os antes los tr\u00e1mites de un complicado divorcio, pero el proceso no hab\u00eda concluido a\u00fan cuando el l\u00edder lesotense volvi\u00f3 a ser elegido \u2013 por segunda vez en su carrera \u2013 para ocupar el cargo de primer ministro. Un mes despu\u00e9s de la muerte, Thabane contrajo matrimonio con Maesaiah y \u00e9sta pas\u00f3 a ser oficialmente primera dama del pa\u00eds. Las especulaciones sobre la presunta implicaci\u00f3n de Maesaiah en el crimen no son nuevas, si bien la situaci\u00f3n de los Thabane se complic\u00f3 especialmente a partir de diciembre de 2019. En esas fechas sali\u00f3 a la luz de una carta del jefe de la Polic\u00eda del pa\u00eds, Holomo Molibeli, en la que afirmaba tener pruebas de que se hab\u00edan hecho llamadas al n\u00famero del primer ministro desde el lugar de la muerte de Lipo Lelo Thabane. Las acusaciones se conocieron, adem\u00e1s, tras meses de grave crisis interna en el seno del oficialista Congreso de Todos los Basoto (ABC, por sus siglas en ingl\u00e9s), con lo que los afines a Thabane y a su actual esposa relacionaron \u2013 y contin\u00faan relacionando \u2013 las acusaciones con las aspiraciones pol\u00edticas de las facciones rivales. La primera dama tuvo que comparecer el pasado martes en una vista judicial preliminar como acusada de asesinato y deber\u00e1 volver a hacerlo el pr\u00f3ximo 17 de marzo. Su situaci\u00f3n actual es de libertad bajo fianza, pese a que en enero la mujer huy\u00f3 brevemente a Sud\u00e1frica, ayudada por su portavoz, cuando la Polic\u00eda la cit\u00f3 a declarar (sin haber interpuesto a\u00fan cargos) y permaneci\u00f3 en paradero desconocido durante unos d\u00edas. El propio partido ABC tiene problemas para elegir al posible sucesor de Thabane y se debate entre varios aspirantes rivales. Esta situaci\u00f3n amenaza con desatar una nueva oleada de inestabilidad pol\u00edtica en este peque\u00f1o reino monta\u00f1oso enclavado geogr\u00e1ficamente en medio de Sud\u00e1frica. La monarqu\u00eda constitucional de Lesoto, encabezada actualmente por el rey Letsie III, quien no tiene poder ejecutivo, ha vivido numerosos golpes de Estado desde que el pa\u00eds se independiz\u00f3 del Reino Unido en 1966.<\/p>\n","protected":false},"author":6,"featured_media":99659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-99658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture"],"_links":{"self":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/99658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/comments?post=99658"}],"version-history":[{"count":1,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/99658\/revisions"}],"predecessor-version":[{"id":99660,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/posts\/99658\/revisions\/99660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media\/99659"}],"wp:attachment":[{"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/media?parent=99658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/categories?post=99658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conexiondigital.com.do\/index.php\/wp-json\/wp\/v2\/tags?post=99658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}